{"id":14134,"date":"2020-07-02T04:00:14","date_gmt":"2020-07-02T04:00:14","guid":{"rendered":"https:\/\/renacimientomarbella.com\/?page_id=14134"},"modified":"2020-07-02T04:00:57","modified_gmt":"2020-07-02T04:00:57","slug":"nuestro-equipo","status":"publish","type":"page","link":"https:\/\/renacimientomarbella.com\/en\/nuestro-equipo","title":{"rendered":"Our team"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1588951548167 thsn-row thsn-bg-color-yes thsn-bg-color-light thsn-zindex-zero thsn-bgimage-over-bgcolor vc_row-has-fill\">\r\n\t\t\t<div class=\"wpb_column vc_column_container vc_col-sm-12 thsn-column thsn-bg-color-yes thsn-bg-color-transparent thsn-zindex-zero\">\r\n\t<div class=\"vc_column-inner\">\r\n\t\t\t<div class=\"wpb_wrapper\">\r\n\t\t\t<div  class=\"themesion-element themesion-element-team thsn-element-team-style-2 themesion-element-viewtype-row-column themesion-gap-10px thsn-sortable-no\" data-show=\"3\" data-columns=\"3\" data-loop=\"false\" data-autoplay=\"false\" data-center=\"false\" data-nav=\"false\" data-dots=\"false\" data-autoplayspeed=\"1000\" data-margin=\"10px\"><div class=\"themesion-element-inner\"><div class=\"thsn-ele-header-area\"><div class=\"thsn-team-ele-heading\"><div  class=\"thsn-ihbox thsn-ihbox-style-hsbox  thsn-reverse-heading-yes thsn-align-center\" >\r\n\t\t\t\t\t<div class=\"thsn-ihbox-contents\">\r\n\t\t\t<div class=\"thsn-ihbox-subheading\"><\/div>\t\t\t<div class=\"thsn-ihbox-heading\"><\/div>\t\t\t<div class=\"thsn-ihbox-content\">We introduce you to our team led by Dr. Joaqu\u00edn Garc\u00eda Aparicio <\/div>\t\t\t\t\t<\/div><!-- .thsn-ihbox-contents -->\r\n\t\t\t<\/div>\r\n<\/div><\/div><div class=\"thsn-element-posts-wrapper row multi-columns-row\"><div class=\"thsn-ele thsn-team-ele col-md-4\"><article class=\"themesion-ele themesion-ele-team thsn-team-style-2\">\r\n\t<div class=\"themesion-post-item\">\r\n\t\t<div class=\"themesion-team-image-box\">\t\t\t\r\n\t\t\t<div class=\"thsn-featured-wrapper\"><a title=\"Dr. Joaqu\u00edn Garc\u00eda Aparicio\" href=\"https:\/\/renacimientomarbella.com\/en\/Equipo Clinica Renacimiento\/dr-joaquin-garcia-aparicio\"><img loading=\"lazy\" decoding=\"async\" width=\"597\" height=\"597\" src=\"https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2020\/06\/cirujano-dr-joaquin-garcia-aparicio.png\" class=\"attachment-thsn-img-770x770 size-thsn-img-770x770 wp-post-image\" alt=\"\" srcset=\"https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2020\/06\/cirujano-dr-joaquin-garcia-aparicio.png 597w, https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2020\/06\/cirujano-dr-joaquin-garcia-aparicio-300x300.png 300w, https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2020\/06\/cirujano-dr-joaquin-garcia-aparicio-150x150.png 150w, https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2020\/06\/cirujano-dr-joaquin-garcia-aparicio-12x12.png 12w\" sizes=\"(max-width: 597px) 100vw, 597px\" data-id=\"14349\" \/><\/a><\/div>\t\t<\/div>\r\n\t\t<div class=\"themesion-box-content\">\r\n\t\t\t<div class=\"themesion-box-content-inner\">\t\t\t\t\r\n\t\t\t\t<h3 class=\"thsn-team-title\"><a title=\"Dr. Joaqu\u00edn Garc\u00eda Aparicio\" href=\"https:\/\/renacimientomarbella.com\/en\/Equipo%20Clinica%20Renacimiento\/dr-joaquin-garcia-aparicio\">Dr. Joaqu\u00edn Garc\u00eda Aparicio<\/a><\/h3>\r\n\t\t\t\t<div class=\"themesion-box-team-position\">\r\n\t\t\t\t\t\t\t<div class=\"themesion-box-team-position\">Medical Director and Surgeon<\/div>\r\n\t\t\t\t\t\t<\/div>\t\r\n\t\t\t\t<div class=\"themesion-box-social-links\"><ul class=\"thsn-social-links thsn-team-social-links\"><li class=\"thsn-social-li thsn-social-facebook\"><a title=\"thsn-base-icon-facebook-squared\" href=\"https:\/\/www.facebook.com\/Clinica.Renacimiento.Marbella\" target=\"_blank\"><span><i class=\"thsn-base-icon-facebook-squared\"><\/i><\/span><\/a><\/li><li class=\"thsn-social-li thsn-social-twitter\"><a title=\"thsn-base-icon-twitter\" href=\"https:\/\/twitter.com\/clinicamadrid\" target=\"_blank\"><span><i class=\"thsn-base-icon-twitter\"><\/i><\/span><\/a><\/li><li class=\"thsn-social-li thsn-social-youtube\"><a title=\"thsn-base-icon-youtube-play\" href=\"https:\/\/www.youtube.com\/channel\/UCGguanjUSJnQ_yQzhVa10Yw\" target=\"_blank\"><span><i class=\"thsn-base-icon-youtube-play\"><\/i><\/span><\/a><\/li><li class=\"thsn-social-li thsn-social-instagram\"><a title=\"thsn-base-icon-instagram\" href=\"https:\/\/www.instagram.com\/clinicarenacimiento\/\" target=\"_blank\"><span><i class=\"thsn-base-icon-instagram\"><\/i><\/span><\/a><\/li><\/ul><\/div>\t\r\n\t\t\t<\/div>\t\t\t\t\r\n\t\t<\/div>\t\t\r\n\t<\/div>\r\n<\/article>\r\n <\/div><div class=\"thsn-ele thsn-team-ele col-md-4\"><article class=\"themesion-ele themesion-ele-team thsn-team-style-2\">\r\n\t<div class=\"themesion-post-item\">\r\n\t\t<div class=\"themesion-team-image-box\">\t\t\t\r\n\t\t\t<div class=\"thsn-featured-wrapper\"><a title=\"Doctor Andr\u00e9s Merlo Morales\" href=\"https:\/\/renacimientomarbella.com\/en\/Equipo Clinica Renacimiento\/doctor-andres-merlo-morales\"><img loading=\"lazy\" decoding=\"async\" width=\"597\" height=\"597\" src=\"https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2020\/06\/doctor-andres-merlo-microinjerto.jpg\" class=\"attachment-thsn-img-770x770 size-thsn-img-770x770 wp-post-image\" alt=\"\" srcset=\"https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2020\/06\/doctor-andres-merlo-microinjerto.jpg 597w, https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2020\/06\/doctor-andres-merlo-microinjerto-300x300.jpg 300w, https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2020\/06\/doctor-andres-merlo-microinjerto-150x150.jpg 150w\" sizes=\"(max-width: 597px) 100vw, 597px\" data-id=\"14015\" \/><\/a><\/div>\t\t<\/div>\r\n\t\t<div class=\"themesion-box-content\">\r\n\t\t\t<div class=\"themesion-box-content-inner\">\t\t\t\t\r\n\t\t\t\t<h3 class=\"thsn-team-title\"><a title=\"Doctor Andr\u00e9s Merlo Morales\" href=\"https:\/\/renacimientomarbella.com\/en\/Equipo%20Clinica%20Renacimiento\/doctor-andres-merlo-morales\">Doctor Andr\u00e9s Merlo Morales<\/a><\/h3>\r\n\t\t\t\t<div class=\"themesion-box-team-position\">\r\n\t\t\t\t\t\t\t<div class=\"themesion-box-team-position\">Plastic Surgeon<\/div>\r\n\t\t\t\t\t\t<\/div>\t\r\n\t\t\t\t<div class=\"themesion-box-social-links\"><ul class=\"thsn-social-links thsn-team-social-links\"><li class=\"thsn-social-li thsn-social-facebook\"><a title=\"thsn-base-icon-facebook-squared\" href=\"https:\/\/www.facebook.com\/RenacimientoMarbella\" target=\"_blank\"><span><i class=\"thsn-base-icon-facebook-squared\"><\/i><\/span><\/a><\/li><\/ul><\/div>\t\r\n\t\t\t<\/div>\t\t\t\t\r\n\t\t<\/div>\t\t\r\n\t<\/div>\r\n<\/article>\r\n <\/div><div class=\"thsn-ele thsn-team-ele col-md-4\"><article class=\"themesion-ele themesion-ele-team thsn-team-style-2\">\r\n\t<div class=\"themesion-post-item\">\r\n\t\t<div class=\"themesion-team-image-box\">\t\t\t\r\n\t\t\t<div class=\"thsn-featured-wrapper\"><a title=\"Gloria Garc\u00eda-Brazales &#8211; Est\u00e9tica\" href=\"https:\/\/renacimientomarbella.com\/en\/Equipo Clinica Renacimiento\/gloria-garcia-brazales\"><img loading=\"lazy\" decoding=\"async\" width=\"597\" height=\"597\" src=\"https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2020\/04\/gloria-clinica-renacimiento.jpg\" class=\"attachment-thsn-img-770x770 size-thsn-img-770x770 wp-post-image\" alt=\"imagen de gloria clinica renacimiento\" srcset=\"https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2020\/04\/gloria-clinica-renacimiento.jpg 300w, https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2020\/04\/gloria-clinica-renacimiento.jpg 150w, https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2020\/04\/gloria-clinica-renacimiento.jpg 597w\" sizes=\"(max-width: 597px) 100vw, 597px\" data-id=\"13265\" \/><\/a><\/div>\t\t<\/div>\r\n\t\t<div class=\"themesion-box-content\">\r\n\t\t\t<div class=\"themesion-box-content-inner\">\t\t\t\t\r\n\t\t\t\t<h3 class=\"thsn-team-title\"><a title=\"Gloria Garc\u00eda-Brazales &#8211; Est\u00e9tica\" href=\"https:\/\/renacimientomarbella.com\/en\/Equipo%20Clinica%20Renacimiento\/gloria-garcia-brazales\">Gloria Garc\u00eda-Brazales - Aesthetics<\/a><\/h3>\r\n\t\t\t\t<div class=\"themesion-box-team-position\">\r\n\t\t\t\t\t\t\t<div class=\"themesion-box-team-position\">Patient Care<\/div>\r\n\t\t\t\t\t\t<\/div>\t\r\n\t\t\t\t<div class=\"themesion-box-social-links\"><ul class=\"thsn-social-links thsn-team-social-links\"><li class=\"thsn-social-li thsn-social-facebook\"><a title=\"thsn-base-icon-facebook-squared\" href=\"https:\/\/www.facebook.com\/Clinica.Renacimiento.Marbella\" target=\"_blank\"><span><i class=\"thsn-base-icon-facebook-squared\"><\/i><\/span><\/a><\/li><li class=\"thsn-social-li thsn-social-twitter\"><a title=\"thsn-base-icon-twitter\" href=\"https:\/\/twitter.com\/clinicamadrid\" target=\"_blank\"><span><i class=\"thsn-base-icon-twitter\"><\/i><\/span><\/a><\/li><li class=\"thsn-social-li thsn-social-youtube\"><a title=\"thsn-base-icon-youtube-play\" href=\"https:\/\/www.youtube.com\/channel\/UCGguanjUSJnQ_yQzhVa10Yw\" target=\"_blank\"><span><i class=\"thsn-base-icon-youtube-play\"><\/i><\/span><\/a><\/li><li class=\"thsn-social-li thsn-social-instagram\"><a title=\"thsn-base-icon-instagram\" href=\"https:\/\/www.instagram.com\/clinicarenacimiento\/\" target=\"_blank\"><span><i class=\"thsn-base-icon-instagram\"><\/i><\/span><\/a><\/li><\/ul><\/div>\t\r\n\t\t\t<\/div>\t\t\t\t\r\n\t\t<\/div>\t\t\r\n\t<\/div>\r\n<\/article>\r\n <\/div><\/div><\/div><!-- .themesion-element-inner -->   <\/div><!-- .themesion-element -->  \t\t<\/div>\r\n\t<\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"vc_row-full-width vc_clearfix\"><\/div><div id=\"citas\" data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1586702769652 thsn-row thsn-text-color-yes thsn-text-color-white thsn-bg-color-yes thsn-bg-color-gradientcolor thsn-zindex-zero thsn-bgimage-over-bgcolor vc_row-has-fill vc_row-o-content-middle vc_row-flex\">\r\n\t\t\t<div class=\"wpb_column vc_column_container vc_col-sm-8 thsn-column thsn-bg-color-yes thsn-bg-color-transparent thsn-zindex-zero\">\r\n\t<div class=\"vc_column-inner\">\r\n\t\t\t<div class=\"wpb_wrapper\">\r\n\t\t\t<div  class=\"thsn-ihbox thsn-ihbox-style-10  thsn-reverse-heading-yes\" >\r\n\t<div class=\"thsn-ihbox-contents\">\r\n\t\t<div class=\"thsn-ihbox-headingicon d-flex align-items-center\">\r\n\t\t\t<div class=\"thsn-ihbox-icon\"><div class=\"thsn-ihbox-icon-wrapper\"><i class=\"thsn-dentiq-icon thsn-dentiq-icon-doctor\"><\/i><\/div><\/div>\t\t\t<div class=\"thsn-ihbox-contents\">\r\n\t\t\t\t<div class=\"thsn-ihbox-subheading\"><\/div>\t\t\t\t<div class=\"thsn-ihbox-heading\"><\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .thsn-ihbox-contents -->\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div>\r\n<div class=\"wpb_column vc_column_container vc_col-sm-4 thsn-column thsn-bg-color-yes thsn-bg-color-transparent thsn-zindex-zero thsn-responsive-custom-63721479\">\r\n\t<div class=\"vc_column-inner\">\r\n\t\t\t<div class=\"wpb_wrapper\">\r\n\t\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><center><div class=\"latepoint-book-button os_trigger_booking\"   data-nonce=\"737e25d46c\">Book Appointment<\/div><\/center><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1588951222322 thsn-row thsn-bg-color-yes thsn-bg-color-white thsn-zindex-zero thsn-bgimage-position-center-center thsn-bgimage-over-bgcolor vc_row-has-fill\">\r\n\t\t\t<div class=\"wpb_column vc_column_container vc_col-sm-12 thsn-column thsn-bg-color-yes thsn-bg-color-transparent thsn-zindex-zero\">\r\n\t<div class=\"vc_column-inner\">\r\n\t\t\t<div class=\"wpb_wrapper\">\r\n\t\t\t<div  class=\"themesion-element themesion-element-testimonial thsn-element-testimonial-style-1 themesion-element-viewtype-carousel thsn-sortable-no\" data-show=\"-1\" data-columns=\"1\" data-loop=\"false\" data-autoplay=\"true\" data-center=\"false\" data-nav=\"true\" data-dots=\"true\" data-autoplayspeed=\"3500\" data-margin=\"\"><div class=\"themesion-element-inner\"><div class=\"thsn-ele-header-area\"><div  class=\"thsn-ihbox thsn-ihbox-style-hsbox  thsn-reverse-heading-yes thsn-align-center\" >\r\n\t\t\t\t\t<div class=\"thsn-ihbox-contents\">\r\n\t\t\t<div class=\"thsn-ihbox-subheading\"><\/div>\t\t\t<div class=\"thsn-ihbox-heading\"><\/div>\t\t\t<div class=\"thsn-ihbox-content\">Our clients say about Renaissance Clinic Marbella <\/div>\t\t\t\t\t<\/div><!-- .thsn-ihbox-contents -->\r\n\t\t\t<\/div>\r\n<\/div><div class=\"thsn-element-posts-wrapper row multi-columns-row\"><div class=\"thsn-ele thsn-testimonial-ele col-md-12 company\"><article class=\"themesion-ele themesion-ele-testimonial thsn-testimonial-style-1 thsn-testimonial-active\"><div class=\"themesion-post-item\">\r\n\t<div class=\"themesion-box-content\">\t\t    \r\n\t\t<div class=\"themesion-box-desc\">\r\n\t\t\t<blockquote class=\"themesion-testimonial-text\"><p style=\"text-align: center;\">\u00abI stayed as I wanted, what I asked for was what was done to me. Whenever a friend asks me, I send her directly to the Renaissance Madrid clinic \u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><\/p>\n<\/blockquote>\r\n\t\t<\/div>\t\r\n\t\t<div class=\"themesion-box-star-ratings\"><i class=\"thsn-base-icon-star thsn-active\"><\/i><i class=\"thsn-base-icon-star thsn-active\"><\/i><i class=\"thsn-base-icon-star thsn-active\"><\/i><i class=\"thsn-base-icon-star thsn-active\"><\/i><i class=\"thsn-base-icon-star thsn-active\"><\/i><\/div>\t\r\n\t\t<div class=\"d-flex\">\r\n\t\t\t<div class=\"themesion-box-img\"><div class=\"thsn-featured-wrapper\"><a title=\"Patient Dr. Garc\u00eda Aparicio\" href=\"https:\/\/renacimientomarbella.com\/en\/testimonial\/paciente-dr-garcia-aparicio\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2018\/02\/Captura-de-pantalla-2020-04-12-a-las-5.27.21-p.-m.-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"imagen de Opini\u00f3n 1 - Cl\u00ednica Renacimiento Marbella\" srcset=\"https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2018\/02\/Captura-de-pantalla-2020-04-12-a-las-5.27.21-p.-m.-150x150.png 150w, https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2018\/02\/Captura-de-pantalla-2020-04-12-a-las-5.27.21-p.-m.-300x300.png 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" data-id=\"12550\" \/><\/a><\/div><\/div>\t\t\t\r\n\t\t<div class=\"themesion-box-author\">\r\n\t\t\t<h3 class=\"themesion-box-title\">Patient Dr. Garc\u00eda Aparicio<\/h3>\t\t\t\r\n\t\t\t<span class=\"thsn-designation\">Patient<\/span>\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\t\r\n<\/div><\/article><\/div><div class=\"thsn-ele thsn-testimonial-ele col-md-12 general\"><article class=\"themesion-ele themesion-ele-testimonial thsn-testimonial-style-1\"><div class=\"themesion-post-item\">\r\n\t<div class=\"themesion-box-content\">\t\t    \r\n\t\t<div class=\"themesion-box-desc\">\r\n\t\t\t<blockquote class=\"themesion-testimonial-text\"><p style=\"text-align: center;\">\u00abI was informed about the treatments, the cases carried out by Dr. Garc\u00eda-Aparicio and his career and I had it clear, I had to do it at the Renaissance Madrid Clinic\u00bb<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><\/p>\n<\/blockquote>\r\n\t\t<\/div>\t\r\n\t\t<div class=\"themesion-box-star-ratings\"><i class=\"thsn-base-icon-star thsn-active\"><\/i><i class=\"thsn-base-icon-star thsn-active\"><\/i><i class=\"thsn-base-icon-star thsn-active\"><\/i><i class=\"thsn-base-icon-star thsn-active\"><\/i><i class=\"thsn-base-icon-star thsn-active\"><\/i><\/div>\t\r\n\t\t<div class=\"d-flex\">\r\n\t\t\t<div class=\"themesion-box-img\"><div class=\"thsn-featured-wrapper\"><a title=\"Patient Dr. Joaqu\u00edn Garc\u00eda-Aparicio\" href=\"https:\/\/renacimientomarbella.com\/en\/testimonial\/paciente-dr-joaquin-garcia-aparicio-2\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2018\/02\/Captura-de-pantalla-2020-04-12-a-las-6.22.39-p.-m.-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"imagen de Paciente Dr. Garc\u00eda-Aparicio opini\u00f3n\" srcset=\"https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2018\/02\/Captura-de-pantalla-2020-04-12-a-las-6.22.39-p.-m.-150x150.png 150w, https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2018\/02\/Captura-de-pantalla-2020-04-12-a-las-6.22.39-p.-m.-632x635.png 632w, https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2018\/02\/Captura-de-pantalla-2020-04-12-a-las-6.22.39-p.-m.-300x300.png 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" data-id=\"12561\" \/><\/a><\/div><\/div>\t\t\t\r\n\t\t<div class=\"themesion-box-author\">\r\n\t\t\t<h3 class=\"themesion-box-title\">Patient Dr. Joaqu\u00edn Garc\u00eda-Aparicio<\/h3>\t\t\t\r\n\t\t\t<span class=\"thsn-designation\">Patient<\/span>\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\t\r\n<\/div><\/article><\/div><div class=\"thsn-ele thsn-testimonial-ele col-md-12 company\"><article class=\"themesion-ele themesion-ele-testimonial thsn-testimonial-style-1\"><div class=\"themesion-post-item\">\r\n\t<div class=\"themesion-box-content\">\t\t    \r\n\t\t<div class=\"themesion-box-desc\">\r\n\t\t\t<blockquote class=\"themesion-testimonial-text\"><p style=\"text-align: center;\">\u00abI consulted at least 5 clinics before choosing Renaissance Clinic Madrid. They were transparent at all times, they gave me the prices over the phone and Dr. Garcia Aparicio explained to me very detailed and easy to understand the whole process \u00bb.<\/p>\n<p><\/br><\/p>\n<p style=\"text-align: center;\"><\/p>\n<\/blockquote>\r\n\t\t<\/div>\t\r\n\t\t<div class=\"themesion-box-star-ratings\"><i class=\"thsn-base-icon-star thsn-active\"><\/i><i class=\"thsn-base-icon-star thsn-active\"><\/i><i class=\"thsn-base-icon-star thsn-active\"><\/i><i class=\"thsn-base-icon-star thsn-active\"><\/i><i class=\"thsn-base-icon-star thsn-active\"><\/i><\/div>\t\r\n\t\t<div class=\"d-flex\">\r\n\t\t\t<div class=\"themesion-box-img\"><div class=\"thsn-featured-wrapper\"><a title=\"Patient Dr. Garc\u00eda-Aparicio\" href=\"https:\/\/renacimientomarbella.com\/en\/testimonial\/paciente-dr-garcia-aparicio-3\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2020\/04\/clinica-renacimiento-madrid-home-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2020\/04\/clinica-renacimiento-madrid-home-150x150.jpg 150w, https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2020\/04\/clinica-renacimiento-madrid-home-770x770.jpg 770w, https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2020\/04\/clinica-renacimiento-madrid-home-300x300.jpg 300w\" sizes=\"(max-width: 150px) 100vw, 150px\" data-id=\"12563\" \/><\/a><\/div><\/div>\t\t\t\r\n\t\t<div class=\"themesion-box-author\">\r\n\t\t\t<h3 class=\"themesion-box-title\">Patient Dr. Garc\u00eda-Aparicio<\/h3>\t\t\t\r\n\t\t\t<span class=\"thsn-designation\">Patient<\/span>\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\t\r\n<\/div><\/article><\/div><\/div><\/div><!-- .themesion-element-inner -->   <\/div><!-- .themesion-element -->  \t\t<\/div>\r\n\t<\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1563512482202 thsn-row thsn-bg-color-yes thsn-bg-color-white thsn-zindex-zero vc_row-has-fill\">\r\n\t\t\t<div class=\"wpb_column vc_column_container vc_col-sm-12 thsn-column thsn-bg-color-yes thsn-bg-color-transparent thsn-zindex-zero\">\r\n\t<div class=\"vc_column-inner\">\r\n\t\t\t<div class=\"wpb_wrapper\">\r\n\t\t\t<div  class=\"themesion-element themesion-element-thsn-client thsn-element-thsn-client-style-1 themesion-element-viewtype-carousel thsn-sortable-no\" data-show=\"11\" data-columns=\"5\" data-loop=\"false\" data-autoplay=\"true\" data-center=\"false\" data-nav=\"false\" data-dots=\"true\" data-autoplayspeed=\"1000\" data-margin=\"\"><div class=\"themesion-element-inner\"><div class=\"thsn-ele-header-area\"><\/div><div class=\"thsn-element-posts-wrapper row multi-columns-row\"><div class=\"thsn-ele thsn-client-ele col-md-20percent\"><article class=\"themesion-ele themesion-ele-client thsn-client-style-1\"><div class=\"thsn-client-wrapper\">\r\n\t<h4 class=\"thsn-hide\">Client 4<\/h4>\r\n\t\t<div class=\"thsn-featured-wrapper\"><a title=\"Client 4\" href=\"https:\/\/renacimientomarbella.com\/en\/client\/client-4\"><img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"76\" src=\"https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2019\/03\/icomem.jpg\" class=\"attachment-thsn-img-770x9999 size-thsn-img-770x9999 wp-post-image\" alt=\"\" data-id=\"12355\" \/><\/a><\/div>\t\t<\/div><\/article><\/div><div class=\"thsn-ele thsn-client-ele col-md-20percent\"><article class=\"themesion-ele themesion-ele-client thsn-client-style-1\"><div class=\"thsn-client-wrapper\">\r\n\t<h4 class=\"thsn-hide\">Client 2<\/h4>\r\n\t\t<div class=\"thsn-featured-wrapper\"><a title=\"Client 2\" href=\"https:\/\/renacimientomarbella.com\/en\/client\/client-2\"><img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"76\" src=\"https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2019\/03\/comunidad-madrid.jpg\" class=\"attachment-thsn-img-770x9999 size-thsn-img-770x9999 wp-post-image\" alt=\"\" data-id=\"12356\" \/><\/a><\/div>\t\t<\/div><\/article><\/div><div class=\"thsn-ele thsn-client-ele col-md-20percent\"><article class=\"themesion-ele themesion-ele-client thsn-client-style-1\"><div class=\"thsn-client-wrapper thsn-client-with-hover-img\">\r\n\t<h4 class=\"thsn-hide\">Secpre Logo<\/h4>\r\n\t\t\t<div class=\"thsn-client-hover-img\"><img decoding=\"async\" src=\"https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2020\/06\/logo-secpre-clinica-renacimiento.png\" \/><\/div>\t<\/div><\/article><\/div><div class=\"thsn-ele thsn-client-ele col-md-20percent\"><article class=\"themesion-ele themesion-ele-client thsn-client-style-1\"><div class=\"thsn-client-wrapper\">\r\n\t<h4 class=\"thsn-hide\">Client 1<\/h4>\r\n\t\t<div class=\"thsn-featured-wrapper\"><a title=\"Client 1\" href=\"https:\/\/renacimientomarbella.com\/en\/client\/client-1\"><img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"76\" src=\"https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2019\/03\/seme.jpg\" class=\"attachment-thsn-img-770x9999 size-thsn-img-770x9999 wp-post-image\" alt=\"\" data-id=\"12357\" \/><\/a><\/div>\t\t<\/div><\/article><\/div><div class=\"thsn-ele thsn-client-ele col-md-20percent\"><article class=\"themesion-ele themesion-ele-client thsn-client-style-1\"><div class=\"thsn-client-wrapper\">\r\n\t<h4 class=\"thsn-hide\">Client 6<\/h4>\r\n\t\t<div class=\"thsn-featured-wrapper\"><a title=\"Client 6\" href=\"https:\/\/renacimientomarbella.com\/en\/client\/client-6\"><img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"76\" src=\"https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2019\/03\/sece.jpg\" class=\"attachment-thsn-img-770x9999 size-thsn-img-770x9999 wp-post-image\" alt=\"\" data-id=\"12358\" \/><\/a><\/div>\t\t<\/div><\/article><\/div><div class=\"thsn-ele thsn-client-ele col-md-20percent\"><article class=\"themesion-ele themesion-ele-client thsn-client-style-1\"><div class=\"thsn-client-wrapper\">\r\n\t<h4 class=\"thsn-hide\">Client 7<\/h4>\r\n\t\t<div class=\"thsn-featured-wrapper\"><a title=\"Client 7\" href=\"https:\/\/renacimientomarbella.com\/en\/client\/client-7\"><img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"76\" src=\"https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2020\/04\/secc-1.jpg\" class=\"attachment-thsn-img-770x9999 size-thsn-img-770x9999 wp-post-image\" alt=\"\" data-id=\"12573\" \/><\/a><\/div>\t\t<\/div><\/article><\/div><div class=\"thsn-ele thsn-client-ele col-md-20percent\"><article class=\"themesion-ele themesion-ele-client thsn-client-style-1\"><div class=\"thsn-client-wrapper\">\r\n\t<h4 class=\"thsn-hide\">Client 8<\/h4>\r\n\t\t<div class=\"thsn-featured-wrapper\"><a title=\"Client 8\" href=\"https:\/\/renacimientomarbella.com\/en\/client\/client-8\"><img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"76\" src=\"https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2020\/04\/asmell.jpg\" class=\"attachment-thsn-img-770x9999 size-thsn-img-770x9999 wp-post-image\" alt=\"\" data-id=\"12572\" \/><\/a><\/div>\t\t<\/div><\/article><\/div><div class=\"thsn-ele thsn-client-ele col-md-20percent\"><article class=\"themesion-ele themesion-ele-client thsn-client-style-1\"><div class=\"thsn-client-wrapper\">\r\n\t<h4 class=\"thsn-hide\">Client 9<\/h4>\r\n\t\t<div class=\"thsn-featured-wrapper\"><a title=\"Client 9\" href=\"https:\/\/renacimientomarbella.com\/en\/client\/client-9\"><img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"76\" src=\"https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2020\/04\/fuensanta.jpg\" class=\"attachment-thsn-img-770x9999 size-thsn-img-770x9999 wp-post-image\" alt=\"\" data-id=\"12575\" \/><\/a><\/div>\t\t<\/div><\/article><\/div><div class=\"thsn-ele thsn-client-ele col-md-20percent\"><article class=\"themesion-ele themesion-ele-client thsn-client-style-1\"><div class=\"thsn-client-wrapper\">\r\n\t<h4 class=\"thsn-hide\">Client 10<\/h4>\r\n\t\t<div class=\"thsn-featured-wrapper\"><a title=\"Client 10\" href=\"https:\/\/renacimientomarbella.com\/en\/client\/client-10\"><img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"76\" src=\"https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2020\/04\/amfc.jpg\" class=\"attachment-thsn-img-770x9999 size-thsn-img-770x9999 wp-post-image\" alt=\"\" data-id=\"12571\" \/><\/a><\/div>\t\t<\/div><\/article><\/div><div class=\"thsn-ele thsn-client-ele col-md-20percent\"><article class=\"themesion-ele themesion-ele-client thsn-client-style-1\"><div class=\"thsn-client-wrapper\">\r\n\t<h4 class=\"thsn-hide\">Client 11<\/h4>\r\n\t\t<div class=\"thsn-featured-wrapper\"><a title=\"Client 11\" href=\"https:\/\/renacimientomarbella.com\/en\/client\/client-11\"><img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"76\" src=\"https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2020\/04\/iaa.jpg\" class=\"attachment-thsn-img-770x9999 size-thsn-img-770x9999 wp-post-image\" alt=\"\" data-id=\"12576\" \/><\/a><\/div>\t\t<\/div><\/article><\/div><div class=\"thsn-ele thsn-client-ele col-md-20percent\"><article class=\"themesion-ele themesion-ele-client thsn-client-style-1\"><div class=\"thsn-client-wrapper\">\r\n\t<h4 class=\"thsn-hide\">Client 12<\/h4>\r\n\t\t<div class=\"thsn-featured-wrapper\"><a title=\"Client 12\" href=\"https:\/\/renacimientomarbella.com\/en\/client\/client-12\"><img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"76\" src=\"https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2020\/04\/ispar.jpg\" class=\"attachment-thsn-img-770x9999 size-thsn-img-770x9999 wp-post-image\" alt=\"\" data-id=\"12574\" \/><\/a><\/div>\t\t<\/div><\/article><\/div><\/div><\/div><!-- .themesion-element-inner -->   <\/div><!-- .themesion-element -->  \t\t<\/div>\r\n\t<\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1588951449152 thsn-row thsn-bg-color-yes thsn-bg-color-light thsn-zindex-zero thsn-bgimage-over-bgcolor vc_row-has-fill\">\r\n\t\t\t<div class=\"wpb_column vc_column_container vc_col-sm-12 thsn-column thsn-bg-color-yes thsn-bg-color-transparent thsn-zindex-zero\">\r\n\t<div class=\"vc_column-inner\">\r\n\t\t\t<div class=\"wpb_wrapper\">\r\n\t\t\t<div  class=\"themesion-element themesion-element-blog thsn-element-blog-style-2 themesion-element-viewtype-row-column thsn-sortable-no\" data-show=\"3\" data-columns=\"3\" data-loop=\"false\" data-autoplay=\"false\" data-center=\"false\" data-nav=\"false\" data-dots=\"false\" data-autoplayspeed=\"1000\" data-margin=\"\"><div class=\"themesion-element-inner\"><div class=\"thsn-ele-header-area\"><div  class=\"thsn-ihbox thsn-ihbox-style-hsbox  thsn-reverse-heading-yes thsn-align-center\" >\r\n\t\t\t\t\t<div class=\"thsn-ihbox-contents\">\r\n\t\t\t<div class=\"thsn-ihbox-subheading\"><\/div>\t\t\t<div class=\"thsn-ihbox-heading\"><\/div>\t\t\t<div class=\"thsn-ihbox-content\">Interesting articles to take care of your interior and exterior beauty <\/div>\t\t\t\t\t<\/div><!-- .thsn-ihbox-contents -->\r\n\t\t\t<\/div>\r\n<\/div><div class=\"thsn-element-posts-wrapper row multi-columns-row\"><div class=\"thsn-ele thsn-blog-ele col-md-4 renacimiento-madrid\"><article class=\"themesion-ele themesion-ele-blog thsn-blogbox-style-2 post-14175 post type-post status-publish format-standard has-post-thumbnail hentry category-renacimiento-madrid tag-consejos-exposicion-sol\">\r\n\t<div class=\"post-item\">\r\n\t\t<div class=\"thsn-featured-container\">\t\t\t\t\r\n\t\t\t<div class=\"thsn-featured-wrapper\"><a title=\"Effects of the Sun on the Skin\" href=\"https:\/\/renacimientomarbella.com\/en\/efectos-del-sol-en-la-piel\"><img loading=\"lazy\" decoding=\"async\" width=\"770\" height=\"600\" src=\"https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2021\/06\/Disen\u0303o-sin-ti\u0301tulo-10-770x600.jpg\" class=\"attachment-thsn-img-770x635 size-thsn-img-770x635 wp-post-image\" alt=\"imagen de como protegerse del sol en verano\" data-id=\"14176\" \/><\/a><\/div>\t\r\n\t\t<\/div>\r\n\t\t<div class=\"themesion-box-content\">\t\r\n\t\t\t<div class=\"thsn-meta-container\">\r\n\t\t\t\t<div class=\"thsn-meta-date-wrapper thsn-meta-line\">\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"thsn-meta-date\"><i class=\"thsn-base-icon-calendar-1\"><\/i> Jun 12, 2021<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"thsn-meta-date-wrapper thsn-meta-line\">\t\r\n\t\t\t\t\t<i class=\"thsn-base-icon-comment-empty\"><\/i> <span class=\"thsn-meta thsn-meta-comments\">0<\/span> Comment\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<h3 class=\"thsn-post-title\"><a title=\"Effects of the Sun on the Skin\" href=\"https:\/\/renacimientomarbella.com\/en\/efectos-del-sol-en-la-piel\">Effects of the Sun on the Skin<\/a><\/h3>\r\n \t\t<\/div>\r\n\t<\/div>\r\n<\/article>\r\n<\/div><div class=\"thsn-ele thsn-blog-ele col-md-4 medicina-estetica\"><article class=\"themesion-ele themesion-ele-blog thsn-blogbox-style-2 post-14172 post type-post status-publish format-standard has-post-thumbnail hentry category-medicina-estetica tag-medicina-estetica tag-peeling\">\r\n\t<div class=\"post-item\">\r\n\t\t<div class=\"thsn-featured-container\">\t\t\t\t\r\n\t\t\t<div class=\"thsn-featured-wrapper\"><a title=\"How to prepare the skin for the summer?\" href=\"https:\/\/renacimientomarbella.com\/en\/como-preparar-la-piel-para-el-verano\"><img loading=\"lazy\" decoding=\"async\" width=\"770\" height=\"600\" src=\"https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2021\/06\/Disen\u0303o-sin-ti\u0301tulo-9-770x600.jpg\" class=\"attachment-thsn-img-770x635 size-thsn-img-770x635 wp-post-image\" alt=\"IMAGEN DE COMO PREPARAR LA PIEL PARA EL VERANO\" data-id=\"14173\" \/><\/a><\/div>\t\r\n\t\t<\/div>\r\n\t\t<div class=\"themesion-box-content\">\t\r\n\t\t\t<div class=\"thsn-meta-container\">\r\n\t\t\t\t<div class=\"thsn-meta-date-wrapper thsn-meta-line\">\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"thsn-meta-date\"><i class=\"thsn-base-icon-calendar-1\"><\/i> May 21, 2021<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"thsn-meta-date-wrapper thsn-meta-line\">\t\r\n\t\t\t\t\t<i class=\"thsn-base-icon-comment-empty\"><\/i> <span class=\"thsn-meta thsn-meta-comments\">0<\/span> Comment\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<h3 class=\"thsn-post-title\"><a title=\"How to prepare the skin for the summer?\" href=\"https:\/\/renacimientomarbella.com\/en\/como-preparar-la-piel-para-el-verano\">How to prepare the skin for the summer?<\/a><\/h3>\r\n \t\t<\/div>\r\n\t<\/div>\r\n<\/article>\r\n<\/div><div class=\"thsn-ele thsn-blog-ele col-md-4 medicina-estetica\"><article class=\"themesion-ele themesion-ele-blog thsn-blogbox-style-2 post-14179 post type-post status-publish format-standard has-post-thumbnail hentry category-medicina-estetica tag-acido-hialuronico tag-medicina-estetica tag-peeling\">\r\n\t<div class=\"post-item\">\r\n\t\t<div class=\"thsn-featured-container\">\t\t\t\t\r\n\t\t\t<div class=\"thsn-featured-wrapper\"><a title=\"Monthly skin care\" href=\"https:\/\/renacimientomarbella.com\/en\/cuidados-mensuales-de-la-piel\"><img loading=\"lazy\" decoding=\"async\" width=\"770\" height=\"600\" src=\"https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2021\/06\/Disen\u0303o-sin-ti\u0301tulo-11-770x600.jpg\" class=\"attachment-thsn-img-770x635 size-thsn-img-770x635 wp-post-image\" alt=\"imagen de cuidado de la piel en renacimiento\" data-id=\"14180\" \/><\/a><\/div>\t\r\n\t\t<\/div>\r\n\t\t<div class=\"themesion-box-content\">\t\r\n\t\t\t<div class=\"thsn-meta-container\">\r\n\t\t\t\t<div class=\"thsn-meta-date-wrapper thsn-meta-line\">\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"thsn-meta-date\"><i class=\"thsn-base-icon-calendar-1\"><\/i> May 13, 2021<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"thsn-meta-date-wrapper thsn-meta-line\">\t\r\n\t\t\t\t\t<i class=\"thsn-base-icon-comment-empty\"><\/i> <span class=\"thsn-meta thsn-meta-comments\">0<\/span> Comment\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<h3 class=\"thsn-post-title\"><a title=\"Monthly skin care\" href=\"https:\/\/renacimientomarbella.com\/en\/cuidados-mensuales-de-la-piel\">Monthly skin care<\/a><\/h3>\r\n \t\t<\/div>\r\n\t<\/div>\r\n<\/article>\r\n<\/div><\/div><\/div><!-- .themesion-element-inner -->   <\/div><!-- .themesion-element -->  <div class=\"vc_row wpb_row vc_inner vc_row-fluid thsn-row-inner thsn-bg-color-yes thsn-bg-color-transparent thsn-zindex-zero\">\r\n\t<div class=\"wpb_column vc_column_container vc_col-sm-12 thsn-column-inner thsn-bg-color-yes thsn-bg-color-transparent thsn-zindex-zero\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_btn3-container vc_btn3-center\">\r\n\t<button class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-modern vc_btn3-block vc_btn3-color-globalcolor\"><span>SEE ALL ITEMS<\/span><\/button><\/div>\r\n<\/div><\/div><\/div><\/div>\r\n<div class=\"vc_empty_space\"   style=\"height: 52px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\t\t<\/div>\r\n\t<\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid thsn-overflow-visible vc_custom_1592147030609 thsn-row thsn-bg-color-yes thsn-bg-color-transparent thsn-zindex-2 vc_row-has-fill\">\r\n\t\t\t<div class=\"wpb_column vc_column_container vc_col-sm-5 thsn-column thsn-bg-color-yes thsn-bg-color-transparent thsn-zindex-zero\">\r\n\t<div class=\"vc_column-inner vc_custom_1563604882799\">\r\n\t\t\t<div class=\"wpb_wrapper\">\r\n\t\t\t<h3 style=\"text-align: left\" class=\"vc_custom_heading vc_custom_1589588760833\" >Renaissance Clinic Information<\/h3><div  class=\"thsn-ihbox thsn-ihbox-style-8  vc_custom_1592145987757\" >\r\n\t<div class=\"thsn-ihbox-box\">\r\n\t\t\t<div class=\"thsn-ihbox-headingicon d-flex align-items-center\">\r\n\t\t\t\t<div class=\"thsn-ihbox-icon\"><div class=\"thsn-ihbox-icon-wrapper\"><i class=\"thsn-dentiq-icon thsn-dentiq-icon-placeholder-1\"><\/i><\/div><\/div>\t\t\t\t<div class=\"thsn-heading\">\r\n\t\t\t\t\t<div class=\"thsn-ihbox-heading\"><\/div>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t<div class=\"thsn-ihbox-contents\">\r\n\t\t\t\t<div class=\"thsn-ihbox-content\">Calle Maestra Do\u00f1a Carola, 8, 29600 Marbella, M\u00e1laga<br \/>\nCalle San Juan Bosco, 8, 29601 Marbella, M\u00e1laga <\/div>\t\t\t\t\t\t\t<\/div><!-- .thsn-ihbox-contents -->\r\n\t<\/div>\r\n<\/div>\r\n<div  class=\"thsn-ihbox thsn-ihbox-style-8  vc_custom_1592145997989\" >\r\n\t<div class=\"thsn-ihbox-box\">\r\n\t\t\t<div class=\"thsn-ihbox-headingicon d-flex align-items-center\">\r\n\t\t\t\t<div class=\"thsn-ihbox-icon\"><div class=\"thsn-ihbox-icon-wrapper\"><i class=\"thsn-dentiq-icon thsn-dentiq-icon-call\"><\/i><\/div><\/div>\t\t\t\t<div class=\"thsn-heading\">\r\n\t\t\t\t\t<div class=\"thsn-ihbox-heading\"><\/div>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t<div class=\"thsn-ihbox-contents\">\r\n\t\t\t\t<div class=\"thsn-ihbox-content\">656 82 97 45<br \/>\n(Also Whatsapp) <\/div>\t\t\t\t\t\t\t<\/div><!-- .thsn-ihbox-contents -->\r\n\t<\/div>\r\n<\/div>\r\n<div  class=\"thsn-ihbox thsn-ihbox-style-8\" >\r\n\t<div class=\"thsn-ihbox-box\">\r\n\t\t\t<div class=\"thsn-ihbox-headingicon d-flex align-items-center\">\r\n\t\t\t\t<div class=\"thsn-ihbox-icon\"><div class=\"thsn-ihbox-icon-wrapper\"><i class=\"thsn-dentiq-icon thsn-dentiq-icon-medical-record\"><\/i><\/div><\/div>\t\t\t\t<div class=\"thsn-heading\">\r\n\t\t\t\t\t<div class=\"thsn-ihbox-heading\"><\/div>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t<div class=\"thsn-ihbox-contents\">\r\n\t\t\t\t<div class=\"thsn-ihbox-content\">info@renacimientomarbella.com <\/div>\t\t\t\t\t\t\t<\/div><!-- .thsn-ihbox-contents -->\r\n\t<\/div>\r\n<\/div>\r\n\n\t<div class=\"wpb_raw_code wpb_content_element wpb_raw_html vc_custom_1592146047731\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<iframe loading=\"lazy\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d3206.5446895719506!2d-4.898963484970059!3d36.51685148000787!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0xd72d7f905afa3dd%3A0x754b79d9ba0ac1bd!2sHospital%20Ceram%20Marbella!5e0!3m2!1sen!2ses!4v1592146042475!5m2!1sen!2ses\" width=\"600\" height=\"450\" frameborder=\"0\" style=\"border:0;\" allowfullscreen=\"\" aria-hidden=\"false\" tabindex=\"0\"><\/iframe>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<ul class=\"thsn-social-links\"><li class=\"thsn-social-li thsn-social-facebook\"><a  title=\"thsn-base-icon-facebook-squared\" href=\"#\" target=\"_blank\"><span><i class=\"thsn-base-icon-facebook-squared\"><\/i><\/span><\/a><\/li><li class=\"thsn-social-li thsn-social-twitter\"><a  title=\"thsn-base-icon-twitter\" href=\"#\" target=\"_blank\"><span><i class=\"thsn-base-icon-twitter\"><\/i><\/span><\/a><\/li><li class=\"thsn-social-li thsn-social-linkedin\"><a  title=\"thsn-base-icon-linkedin-squared\" href=\"#\" target=\"_blank\"><span><i class=\"thsn-base-icon-linkedin-squared\"><\/i><\/span><\/a><\/li><li class=\"thsn-social-li thsn-social-instagram\"><a  title=\"thsn-base-icon-instagram\" href=\"#\" target=\"_blank\"><span><i class=\"thsn-base-icon-instagram\"><\/i><\/span><\/a><\/li><\/ul>\n\n\t\t<\/div>\n\t<\/div>\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div>\r\n<div class=\"thsn-contact-box wpb_column vc_column_container vc_col-sm-7 thsn-column thsn-bg-color-yes thsn-bg-color-transparent thsn-zindex-2\">\r\n\t<div class=\"vc_column-inner vc_custom_1563271208092\">\r\n\t\t\t<div class=\"wpb_wrapper\">\r\n\t\t\t<div  class=\"thsn-ihbox thsn-ihbox-style-hsbox   thsn-reverse-heading-yes\" >\r\n\t\t\t\t\t<div class=\"thsn-ihbox-contents\">\r\n\t\t\t<div class=\"thsn-ihbox-subheading\"><\/div>\t\t\t<div class=\"thsn-ihbox-heading\"><\/div>\t\t\t\t\t\t\t\t<\/div><!-- .thsn-ihbox-contents -->\r\n\t\t\t<\/div>\r\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\"><div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-13519\"><form id=\"wpforms-form-13519\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"13519\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/14134\" data-trp-original-action=\"\/en\/wp-json\/wp\/v2\/pages\/14134\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-13519-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label\" for=\"wpforms-13519-field_0\">Name <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-13519-field_0\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][0][first]\" placeholder=\"Name\" required><label for=\"wpforms-13519-field_0\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-13519-field_0-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][0][last]\" placeholder=\"Surnames\" required><label for=\"wpforms-13519-field_0-last\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">Last<\/label><\/div><\/div><\/div><div id=\"wpforms-13519-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-13519-field_1\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-one-half wpforms-first\"><input type=\"email\" id=\"wpforms-13519-field_1\" class=\"wpforms-field-required wpforms-field-email-primary\" name=\"wpforms[fields][1][primary]\" placeholder=\"Your email\" required><label for=\"wpforms-13519-field_1\" class=\"wpforms-field-sublabel after\">E-mail<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"email\" id=\"wpforms-13519-field_1-secondary\" class=\"wpforms-field-email-secondary wpforms-field-required\" data-rule-confirm=\"#wpforms-13519-field_1\" name=\"wpforms[fields][1][secondary]\" placeholder=\"Confirm Your E-mail\" required><label for=\"wpforms-13519-field_1-secondary\" class=\"wpforms-field-sublabel after\">Confirm Email<\/label><\/div><\/div><\/div><div id=\"wpforms-13519-field_3-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-13519-field_3\">Telephone contact <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-13519-field_3\" class=\"wpforms-field-large wpforms-field-required wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][3]\" required><\/div><div id=\"wpforms-13519-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-13519-field_2\">Describe your query in detail <span class=\"wpforms-required-label\">*<\/span><\/label><textarea id=\"wpforms-13519-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" required><\/textarea><\/div><div id=\"wpforms-13519-field_5-container\" class=\"wpforms-field wpforms-field-rating\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-13519-field_5\">Rate your experience on our website<\/label><div class=\"wpforms-field-rating-items\"><label class=\"wpforms-field-rating-item choice-1\" for=\"wpforms-13519-field_5_1\"><span class=\"wpforms-screen-reader-element\">Rate 1 out of 5<\/span><input type=\"radio\" id=\"wpforms-13519-field_5_1\" class=\"wpforms-screen-reader-element\" name=\"wpforms[fields][5]\" value=\"1\" ><svg width=\"28\" height=\"28\" style=\"height:28px;width:28px;\" fill=\"currentColor\" color=\"#e27730\" viewbox=\"0 0 1792 1792\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path  d=\"M1262 1075q-37 121-138 195t-228 74-228-74-138-195q-8-25 4-48.5t38-31.5q25-8 48.5 4t31.5 38q25 80 92.5 129.5t151.5 49.5 151.5-49.5 92.5-129.5q8-26 32-38t49-4 37 31.5 4 48.5zm-494-435q0 53-37.5 90.5t-90.5 37.5-90.5-37.5-37.5-90.5 37.5-90.5 90.5-37.5 90.5 37.5 37.5 90.5zm512 0q0 53-37.5 90.5t-90.5 37.5-90.5-37.5-37.5-90.5 37.5-90.5 90.5-37.5 90.5 37.5 37.5 90.5zm256 256q0-130-51-248.5t-136.5-204-204-136.5-248.5-51-248.5 51-204 136.5-136.5 204-51 248.5 51 248.5 136.5 204 204 136.5 248.5 51 248.5-51 204-136.5 136.5-204 51-248.5zm128 0q0 209-103 385.5t-279.5 279.5-385.5 103-385.5-103-279.5-279.5-103-385.5 103-385.5 279.5-279.5 385.5-103 385.5 103 279.5 279.5 103 385.5z\"\/><\/svg><\/label><label class=\"wpforms-field-rating-item choice-2\" for=\"wpforms-13519-field_5_2\"><span class=\"wpforms-screen-reader-element\">Rate 2 out of 5<\/span><input type=\"radio\" id=\"wpforms-13519-field_5_2\" class=\"wpforms-screen-reader-element\" name=\"wpforms[fields][5]\" value=\"2\" ><svg width=\"28\" height=\"28\" style=\"height:28px;width:28px;\" fill=\"currentColor\" color=\"#e27730\" viewbox=\"0 0 1792 1792\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path  d=\"M1262 1075q-37 121-138 195t-228 74-228-74-138-195q-8-25 4-48.5t38-31.5q25-8 48.5 4t31.5 38q25 80 92.5 129.5t151.5 49.5 151.5-49.5 92.5-129.5q8-26 32-38t49-4 37 31.5 4 48.5zm-494-435q0 53-37.5 90.5t-90.5 37.5-90.5-37.5-37.5-90.5 37.5-90.5 90.5-37.5 90.5 37.5 37.5 90.5zm512 0q0 53-37.5 90.5t-90.5 37.5-90.5-37.5-37.5-90.5 37.5-90.5 90.5-37.5 90.5 37.5 37.5 90.5zm256 256q0-130-51-248.5t-136.5-204-204-136.5-248.5-51-248.5 51-204 136.5-136.5 204-51 248.5 51 248.5 136.5 204 204 136.5 248.5 51 248.5-51 204-136.5 136.5-204 51-248.5zm128 0q0 209-103 385.5t-279.5 279.5-385.5 103-385.5-103-279.5-279.5-103-385.5 103-385.5 279.5-279.5 385.5-103 385.5 103 279.5 279.5 103 385.5z\"\/><\/svg><\/label><label class=\"wpforms-field-rating-item choice-3\" for=\"wpforms-13519-field_5_3\"><span class=\"wpforms-screen-reader-element\">Rate 3 out of 5<\/span><input type=\"radio\" id=\"wpforms-13519-field_5_3\" class=\"wpforms-screen-reader-element\" name=\"wpforms[fields][5]\" value=\"3\" ><svg width=\"28\" height=\"28\" style=\"height:28px;width:28px;\" fill=\"currentColor\" color=\"#e27730\" viewbox=\"0 0 1792 1792\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path  d=\"M1262 1075q-37 121-138 195t-228 74-228-74-138-195q-8-25 4-48.5t38-31.5q25-8 48.5 4t31.5 38q25 80 92.5 129.5t151.5 49.5 151.5-49.5 92.5-129.5q8-26 32-38t49-4 37 31.5 4 48.5zm-494-435q0 53-37.5 90.5t-90.5 37.5-90.5-37.5-37.5-90.5 37.5-90.5 90.5-37.5 90.5 37.5 37.5 90.5zm512 0q0 53-37.5 90.5t-90.5 37.5-90.5-37.5-37.5-90.5 37.5-90.5 90.5-37.5 90.5 37.5 37.5 90.5zm256 256q0-130-51-248.5t-136.5-204-204-136.5-248.5-51-248.5 51-204 136.5-136.5 204-51 248.5 51 248.5 136.5 204 204 136.5 248.5 51 248.5-51 204-136.5 136.5-204 51-248.5zm128 0q0 209-103 385.5t-279.5 279.5-385.5 103-385.5-103-279.5-279.5-103-385.5 103-385.5 279.5-279.5 385.5-103 385.5 103 279.5 279.5 103 385.5z\"\/><\/svg><\/label><label class=\"wpforms-field-rating-item choice-4\" for=\"wpforms-13519-field_5_4\"><span class=\"wpforms-screen-reader-element\">Rate 4 out of 5<\/span><input type=\"radio\" id=\"wpforms-13519-field_5_4\" class=\"wpforms-screen-reader-element\" name=\"wpforms[fields][5]\" value=\"4\" ><svg width=\"28\" height=\"28\" style=\"height:28px;width:28px;\" fill=\"currentColor\" color=\"#e27730\" viewbox=\"0 0 1792 1792\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path  d=\"M1262 1075q-37 121-138 195t-228 74-228-74-138-195q-8-25 4-48.5t38-31.5q25-8 48.5 4t31.5 38q25 80 92.5 129.5t151.5 49.5 151.5-49.5 92.5-129.5q8-26 32-38t49-4 37 31.5 4 48.5zm-494-435q0 53-37.5 90.5t-90.5 37.5-90.5-37.5-37.5-90.5 37.5-90.5 90.5-37.5 90.5 37.5 37.5 90.5zm512 0q0 53-37.5 90.5t-90.5 37.5-90.5-37.5-37.5-90.5 37.5-90.5 90.5-37.5 90.5 37.5 37.5 90.5zm256 256q0-130-51-248.5t-136.5-204-204-136.5-248.5-51-248.5 51-204 136.5-136.5 204-51 248.5 51 248.5 136.5 204 204 136.5 248.5 51 248.5-51 204-136.5 136.5-204 51-248.5zm128 0q0 209-103 385.5t-279.5 279.5-385.5 103-385.5-103-279.5-279.5-103-385.5 103-385.5 279.5-279.5 385.5-103 385.5 103 279.5 279.5 103 385.5z\"\/><\/svg><\/label><label class=\"wpforms-field-rating-item choice-5\" for=\"wpforms-13519-field_5_5\"><span class=\"wpforms-screen-reader-element\">Rate 5 out of 5<\/span><input type=\"radio\" id=\"wpforms-13519-field_5_5\" class=\"wpforms-screen-reader-element\" name=\"wpforms[fields][5]\" value=\"5\" ><svg width=\"28\" height=\"28\" style=\"height:28px;width:28px;\" fill=\"currentColor\" color=\"#e27730\" viewbox=\"0 0 1792 1792\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path  d=\"M1262 1075q-37 121-138 195t-228 74-228-74-138-195q-8-25 4-48.5t38-31.5q25-8 48.5 4t31.5 38q25 80 92.5 129.5t151.5 49.5 151.5-49.5 92.5-129.5q8-26 32-38t49-4 37 31.5 4 48.5zm-494-435q0 53-37.5 90.5t-90.5 37.5-90.5-37.5-37.5-90.5 37.5-90.5 90.5-37.5 90.5 37.5 37.5 90.5zm512 0q0 53-37.5 90.5t-90.5 37.5-90.5-37.5-37.5-90.5 37.5-90.5 90.5-37.5 90.5 37.5 37.5 90.5zm256 256q0-130-51-248.5t-136.5-204-204-136.5-248.5-51-248.5 51-204 136.5-136.5 204-51 248.5 51 248.5 136.5 204 204 136.5 248.5 51 248.5-51 204-136.5 136.5-204 51-248.5zm128 0q0 209-103 385.5t-279.5 279.5-385.5 103-385.5-103-279.5-279.5-103-385.5 103-385.5 279.5-279.5 385.5-103 385.5 103 279.5 279.5 103 385.5z\"\/><\/svg><\/label><\/div><\/div><div id=\"wpforms-13519-field_6-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-13519-field_6\">Legal Notice and Privacy Policy <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-13519-field_6\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-13519-field_6_1\" name=\"wpforms[fields][6][]\" value=\"Acepto la Pol\u00edtica de Privacidad y T\u00e9rminos y Condiciones de Cl\u00ednica Renacimiento Madrid\" required><label class=\"wpforms-field-label-inline\" for=\"wpforms-13519-field_6_1\">I accept the Privacy Policy and Terms and Conditions of the Renaissance Madrid Clinic<\/label><\/li><\/ul><\/div><\/div><div class=\"wpforms-field wpforms-field-hp\"><label for=\"wpforms-13519-field-hp\" class=\"wpforms-field-label\">Phone<\/label><input type=\"text\" name=\"wpforms[hp]\" id=\"wpforms-13519-field-hp\" class=\"wpforms-field-medium\"><\/div><input type=\"hidden\" name=\"wpforms[recaptcha]\" value=\"\"><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"13519\"><input type=\"hidden\" name=\"wpforms[author]\" value=\"1\"><button type=\"submit\" name=\"wpforms[submit]\" class=\"wpforms-submit\" id=\"wpforms-submit-13519\" value=\"wpforms-submit\" aria-live=\"assertive\" data-alt-text=\"Enviando...\" data-submit-text=\"Enviar Solicitud de Contacto\">Send Contact Request<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/renacimientomarbella.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"\"><\/div><input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form><\/div>  <!-- .wpforms-container --><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"step-two how-step\">\n<div class=\"step-content\">\n<div class=\"desc-shortcode\" style=\"text-align: center;\"><div class=\"latepoint-book-button os_trigger_booking\"   data-nonce=\"737e25d46c\">Book Appointment<\/div><\/div>\n<\/div>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"vc_row-full-width vc_clearfix\"><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Si cuidas de tu pelo todos los meses, por qu\u00e9 no cuidas tu piel, que es el \u00f3rgano m\u00e1s expuesto, que m\u00e1s envejece y que m\u00e1s delata el paso de los a\u00f1os. Cubre las necesidades de tu piel mensualmente, llegando donde las cremas de uso diario no llegan. Regenerando tu piel de dentro\u00a0 hacia fuera. [...]","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.7 (Yoast SEO v21.9.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nuestro Equipo - Cl\u00ednica Renacimiento Marbella<\/title>\n<meta name=\"description\" content=\"Nuestro Equipo - Escoge la Cl\u00ednica Renacimiento Madrid para tus Tratamientos de Cirug\u00eda y Medicina es\u00e9tica Facial y Corporal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/renacimientomarbella.com\/en\/nuestro-equipo\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuestro Equipo\" \/>\n<meta property=\"og:description\" content=\"Nuestro Equipo - Escoge la Cl\u00ednica Renacimiento Madrid para tus Tratamientos de Cirug\u00eda y Medicina es\u00e9tica Facial y Corporal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/renacimientomarbella.com\/en\/nuestro-equipo\/\" \/>\n<meta property=\"og:site_name\" content=\"Cl\u00ednica Renacimiento Marbella\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Clinica.Renacimiento.Madrid\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-02T04:00:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2018\/10\/tratamientos-mas-populares-clinica-renacimiento-madrid.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@clinicamadrid\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/renacimientomarbella.com\/nuestro-equipo\",\"url\":\"https:\/\/renacimientomarbella.com\/nuestro-equipo\",\"name\":\"Nuestro Equipo - Cl\u00ednica Renacimiento Marbella\",\"isPartOf\":{\"@id\":\"https:\/\/renacimientomarbella.com\/#website\"},\"datePublished\":\"2020-07-02T04:00:14+00:00\",\"dateModified\":\"2020-07-02T04:00:57+00:00\",\"description\":\"Nuestro Equipo - Escoge la Cl\u00ednica Renacimiento Madrid para tus Tratamientos de Cirug\u00eda y Medicina es\u00e9tica Facial y Corporal.\",\"breadcrumb\":{\"@id\":\"https:\/\/renacimientomarbella.com\/nuestro-equipo#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/renacimientomarbella.com\/nuestro-equipo\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/renacimientomarbella.com\/nuestro-equipo#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/renacimientomarbella.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuestro Equipo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/renacimientomarbella.com\/#website\",\"url\":\"https:\/\/renacimientomarbella.com\/\",\"name\":\"Cl\u00ednica Renacimiento Marbella\",\"description\":\"Cirug\u00eda y Medicina Est\u00e9tica en Marbella\",\"publisher\":{\"@id\":\"https:\/\/renacimientomarbella.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/renacimientomarbella.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":[\"Organization\",\"Place\",\"MedicalClinic\"],\"@id\":\"https:\/\/renacimientomarbella.com\/#organization\",\"name\":\"Cl\u00ednica Renacimiento Madrid\",\"url\":\"https:\/\/renacimientomarbella.com\/\",\"logo\":{\"@id\":\"https:\/\/renacimientomarbella.com\/nuestro-equipo#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\/\/renacimientomarbella.com\/nuestro-equipo#local-main-organization-logo\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Clinica.Renacimiento.Madrid\",\"https:\/\/twitter.com\/clinicamadrid\",\"https:\/\/www.instagram.com\/clinicarenacimiento\/\",\"https:\/\/www.youtube.com\/channel\/UCGguanjUSJnQ_yQzhVa10Yw\"],\"address\":{\"@id\":\"https:\/\/renacimientomarbella.com\/nuestro-equipo#local-main-place-address\"},\"geo\":{\"@type\":\"GeoCoordinates\",\"latitude\":\"40.424108\",\"longitude\":\"-3.6987307\"},\"telephone\":[\"667597332\",\"915619129\"],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\"],\"opens\":\"10:00\",\"closes\":\"20:00\"},{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Saturday\",\"Sunday\"],\"opens\":\"00:00\",\"closes\":\"00:00\"}],\"email\":\"info@renacimientomarbella.com\",\"areaServed\":\"Madrid y Marbella\",\"paymentAccepted\":\"Efectivo, Financiaci\u00f3n, Tarjeta de d\u00e9bito\/cr\u00e9dito, Transferencia bancaria\"},{\"@type\":\"PostalAddress\",\"@id\":\"https:\/\/renacimientomarbella.com\/nuestro-equipo#local-main-place-address\",\"streetAddress\":\"Calle Pr\u00edncipe de Vergara 55, 1\u00baC\",\"addressLocality\":\"Madrid\",\"postalCode\":\"28006\",\"addressRegion\":\"Comunidad de Madrid\",\"addressCountry\":\"ES\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/renacimientomarbella.com\/nuestro-equipo#local-main-organization-logo\",\"url\":\"https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2020\/05\/Logo-Clinica-Renacimiento-Marbella.png\",\"contentUrl\":\"https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2020\/05\/Logo-Clinica-Renacimiento-Marbella.png\",\"width\":155,\"height\":54,\"caption\":\"Cl\u00ednica Renacimiento Madrid\"}]}<\/script>\n<meta name=\"geo.placename\" content=\"Madrid\" \/>\n<meta name=\"geo.position\" content=\"40.424108;-3.6987307\" \/>\n<meta name=\"geo.region\" content=\"Spain\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nuestro Equipo - Cl\u00ednica Renacimiento Marbella","description":"Nuestro Equipo - Escoge la Cl\u00ednica Renacimiento Madrid para tus Tratamientos de Cirug\u00eda y Medicina es\u00e9tica Facial y Corporal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/renacimientomarbella.com\/en\/nuestro-equipo\/","og_locale":"en_GB","og_type":"article","og_title":"Nuestro Equipo","og_description":"Nuestro Equipo - Escoge la Cl\u00ednica Renacimiento Madrid para tus Tratamientos de Cirug\u00eda y Medicina es\u00e9tica Facial y Corporal.","og_url":"https:\/\/renacimientomarbella.com\/en\/nuestro-equipo\/","og_site_name":"Cl\u00ednica Renacimiento Marbella","article_publisher":"https:\/\/www.facebook.com\/Clinica.Renacimiento.Madrid","article_modified_time":"2020-07-02T04:00:57+00:00","og_image":[{"width":1200,"height":1000,"url":"https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2018\/10\/tratamientos-mas-populares-clinica-renacimiento-madrid.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@clinicamadrid","twitter_misc":{"Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/renacimientomarbella.com\/nuestro-equipo","url":"https:\/\/renacimientomarbella.com\/nuestro-equipo","name":"Nuestro Equipo - Cl\u00ednica Renacimiento Marbella","isPartOf":{"@id":"https:\/\/renacimientomarbella.com\/#website"},"datePublished":"2020-07-02T04:00:14+00:00","dateModified":"2020-07-02T04:00:57+00:00","description":"Nuestro Equipo - Escoge la Cl\u00ednica Renacimiento Madrid para tus Tratamientos de Cirug\u00eda y Medicina es\u00e9tica Facial y Corporal.","breadcrumb":{"@id":"https:\/\/renacimientomarbella.com\/nuestro-equipo#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/renacimientomarbella.com\/nuestro-equipo"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/renacimientomarbella.com\/nuestro-equipo#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/renacimientomarbella.com\/"},{"@type":"ListItem","position":2,"name":"Nuestro Equipo"}]},{"@type":"WebSite","@id":"https:\/\/renacimientomarbella.com\/#website","url":"https:\/\/renacimientomarbella.com\/","name":"Cl\u00ednica Renacimiento Marbella","description":"Cirug\u00eda y Medicina Est\u00e9tica en Marbella","publisher":{"@id":"https:\/\/renacimientomarbella.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/renacimientomarbella.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":["Organization","Place","MedicalClinic"],"@id":"https:\/\/renacimientomarbella.com\/#organization","name":"Cl\u00ednica Renacimiento Madrid","url":"https:\/\/renacimientomarbella.com\/","logo":{"@id":"https:\/\/renacimientomarbella.com\/nuestro-equipo#local-main-organization-logo"},"image":{"@id":"https:\/\/renacimientomarbella.com\/nuestro-equipo#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/Clinica.Renacimiento.Madrid","https:\/\/twitter.com\/clinicamadrid","https:\/\/www.instagram.com\/clinicarenacimiento\/","https:\/\/www.youtube.com\/channel\/UCGguanjUSJnQ_yQzhVa10Yw"],"address":{"@id":"https:\/\/renacimientomarbella.com\/nuestro-equipo#local-main-place-address"},"geo":{"@type":"GeoCoordinates","latitude":"40.424108","longitude":"-3.6987307"},"telephone":["667597332","915619129"],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday"],"opens":"10:00","closes":"20:00"},{"@type":"OpeningHoursSpecification","dayOfWeek":["Saturday","Sunday"],"opens":"00:00","closes":"00:00"}],"email":"info@renacimientomarbella.com","areaServed":"Madrid y Marbella","paymentAccepted":"Efectivo, Financiaci\u00f3n, Tarjeta de d\u00e9bito\/cr\u00e9dito, Transferencia bancaria"},{"@type":"PostalAddress","@id":"https:\/\/renacimientomarbella.com\/nuestro-equipo#local-main-place-address","streetAddress":"Calle Pr\u00edncipe de Vergara 55, 1\u00baC","addressLocality":"Madrid","postalCode":"28006","addressRegion":"Comunidad de Madrid","addressCountry":"ES"},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/renacimientomarbella.com\/nuestro-equipo#local-main-organization-logo","url":"https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2020\/05\/Logo-Clinica-Renacimiento-Marbella.png","contentUrl":"https:\/\/renacimientomarbella.com\/wp-content\/uploads\/2020\/05\/Logo-Clinica-Renacimiento-Marbella.png","width":155,"height":54,"caption":"Cl\u00ednica Renacimiento Madrid"}]},"geo.placename":"Madrid","geo.position":{"lat":"40.424108","long":"-3.6987307"},"geo.region":"Spain"},"_links":{"self":[{"href":"https:\/\/renacimientomarbella.com\/en\/wp-json\/wp\/v2\/pages\/14134"}],"collection":[{"href":"https:\/\/renacimientomarbella.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/renacimientomarbella.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/renacimientomarbella.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/renacimientomarbella.com\/en\/wp-json\/wp\/v2\/comments?post=14134"}],"version-history":[{"count":0,"href":"https:\/\/renacimientomarbella.com\/en\/wp-json\/wp\/v2\/pages\/14134\/revisions"}],"wp:attachment":[{"href":"https:\/\/renacimientomarbella.com\/en\/wp-json\/wp\/v2\/media?parent=14134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}